{"id":4499,"date":"2024-09-09T20:19:55","date_gmt":"2024-09-09T20:19:55","guid":{"rendered":"https:\/\/payproglobal.com\/?post_type=sales-tax&#038;p=4499"},"modified":"2026-05-12T06:30:15","modified_gmt":"2026-05-12T06:30:15","slug":"republica-democratica-do-congo","status":"publish","type":"sales-tax","link":"https:\/\/payproglobal.com\/pt_br\/imposto-sobre-vendas-de-saas\/republica-democratica-do-congo\/","title":{"rendered":"Rep\u00fablica Democr\u00e1tica do Congo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>O que \u00e9 o imposto sobre vendas de SaaS na Rep\u00fablica Democr\u00e1tica do Congo? Obtenha insights de especialistas sobre regulamenta\u00e7\u00f5es, limites e emiss\u00e3o de notas fiscais eletr\u00f4nicas, evite penalidades e mantenha a conformidade.<\/p>","protected":false},"author":10,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":true,"content-type":""},"class_list":["post-4499","sales-tax","type-sales-tax","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/payproglobal.com\/pt_br\/wp-json\/wp\/v2\/sales-tax\/4499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/payproglobal.com\/pt_br\/wp-json\/wp\/v2\/sales-tax"}],"about":[{"href":"https:\/\/payproglobal.com\/pt_br\/wp-json\/wp\/v2\/types\/sales-tax"}],"author":[{"embeddable":true,"href":"https:\/\/payproglobal.com\/pt_br\/wp-json\/wp\/v2\/users\/10"}],"wp:attachment":[{"href":"https:\/\/payproglobal.com\/pt_br\/wp-json\/wp\/v2\/media?parent=4499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}